{"id":11532,"date":"2026-05-11T16:15:34","date_gmt":"2026-05-11T16:15:34","guid":{"rendered":"https:\/\/gimm.pt\/news\/maria-do-carmo-fonseca-distinguida-com-medalha-de-honra-da-sociedade-portuguesa-de-autores\/"},"modified":"2026-05-11T16:17:25","modified_gmt":"2026-05-11T16:17:25","slug":"maria-do-carmo-fonseca-distinguida-com-medalha-de-honra-da-sociedade-portuguesa-de-autores","status":"publish","type":"news","link":"https:\/\/gimm.pt\/pt-pt\/not\u00edcias\/maria-do-carmo-fonseca-distinguida-com-medalha-de-honra-da-sociedade-portuguesa-de-autores\/","title":{"rendered":"Maria do Carmo Fonseca distinguida com Medalha de Honra da Sociedade Portuguesa de Autores"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong>Investigadora da Funda\u00e7\u00e3o GIMM tem desempenhado um papel central no desenvolvimento da ci\u00eancia em Portugal, contribuindo para aproximar investiga\u00e7\u00e3o, cultura cient\u00edfica e sociedade.<\/strong><\/p>\n\n<p>A cientista e m\u00e9dica Maria do Carmo Fonseca foi distinguida com a Medalha de Honra da Sociedade Portuguesa de Autores (SPA), uma das mais relevantes distin\u00e7\u00f5es atribu\u00eddas pela institui\u00e7\u00e3o.<\/p>\n\n<p>A decis\u00e3o foi comunicada pela Dire\u00e7\u00e3o e pelo Conselho de Administra\u00e7\u00e3o da SPA, presididos por Jos\u00e9 Jorge Letria, no \u00e2mbito das comemora\u00e7\u00f5es do Dia do Autor Portugu\u00eas. A cerim\u00f3nia de entrega ter\u00e1 lugar no pr\u00f3ximo dia 22 de maio, na Sala-galeria Carlos Paredes, em Lisboa.<\/p>\n\n<p>Reconhecida internacionalmente pelo seu trabalho pioneiro na \u00e1rea da biologia molecular, Maria do Carmo Fonseca tem desempenhado um papel central no desenvolvimento da ci\u00eancia em Portugal, contribuindo para aproximar investiga\u00e7\u00e3o, cultura cient\u00edfica e sociedade.<\/p>\n\n<p>A distin\u00e7\u00e3o da SPA reconhece n\u00e3o apenas o seu percurso cient\u00edfico, mas tamb\u00e9m o impacto cultural e c\u00edvico do conhecimento e da ci\u00eancia na sociedade contempor\u00e2nea.<\/p>\n\n<p>\u201cRecebo esta distin\u00e7\u00e3o com enorme honra e gratid\u00e3o. Entendo-a tamb\u00e9m como um reconhecimento do papel da ci\u00eancia e do conhecimento na constru\u00e7\u00e3o de uma sociedade mais livre, mais cr\u00edtica e mais preparada para o futuro\u201d, afirma Maria do Carmo Fonseca.<\/p>\n\n<p>Professora Catedr\u00e1tica da Faculdade de Medicina da Universidade de Lisboa e investigadora na Funda\u00e7\u00e3o GIMM, Maria do Carmo Fonseca \u00e9 uma das figuras mais influentes da investiga\u00e7\u00e3o biom\u00e9dica portuguesa.<\/p>\n\n<p>Foi distinguida com o Pr\u00e9mio Pessoa em 2010 e presidiu ao Instituto de Medicina Molecular Jo\u00e3o Lobo Antunes (iMM), institui\u00e7\u00e3o de refer\u00eancia internacional que ajudou a fundar e consolidar.<\/p>\n\n<p>Ao longo da sua carreira, destacou-se pelo estudo do splicing do RNA e dos mecanismos gen\u00e9ticos que regulam a express\u00e3o g\u00e9nica \u2013 descobertas com profundas implica\u00e7\u00f5es na compreens\u00e3o e no tratamento de doen\u00e7as humanas.<\/p>\n\n<p>Recentemente, foi nomeada membro do Conselho de Estado pelo Presidente da Rep\u00fablica, Jos\u00e9 Ant\u00f3nio Seguro.<\/p>\n","protected":false},"featured_media":11531,"comment_status":"open","ping_status":"closed","template":"","news_category":[],"news_tag":[],"publications":[],"publication_date":[],"acf":[],"_links":{"self":[{"href":"https:\/\/gimm.pt\/pt-pt\/wp-json\/wp\/v2\/news\/11532"}],"collection":[{"href":"https:\/\/gimm.pt\/pt-pt\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/gimm.pt\/pt-pt\/wp-json\/wp\/v2\/types\/news"}],"replies":[{"embeddable":true,"href":"https:\/\/gimm.pt\/pt-pt\/wp-json\/wp\/v2\/comments?post=11532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimm.pt\/pt-pt\/wp-json\/wp\/v2\/media\/11531"}],"wp:attachment":[{"href":"https:\/\/gimm.pt\/pt-pt\/wp-json\/wp\/v2\/media?parent=11532"}],"wp:term":[{"taxonomy":"news_category","embeddable":true,"href":"https:\/\/gimm.pt\/pt-pt\/wp-json\/wp\/v2\/news_category?post=11532"},{"taxonomy":"news_tag","embeddable":true,"href":"https:\/\/gimm.pt\/pt-pt\/wp-json\/wp\/v2\/news_tag?post=11532"},{"taxonomy":"publications","embeddable":true,"href":"https:\/\/gimm.pt\/pt-pt\/wp-json\/wp\/v2\/publications?post=11532"},{"taxonomy":"publication_date","embeddable":true,"href":"https:\/\/gimm.pt\/pt-pt\/wp-json\/wp\/v2\/publication_date?post=11532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}